{"id":26811,"date":"2026-07-15T12:29:15","date_gmt":"2026-07-15T18:29:15","guid":{"rendered":"https:\/\/angelneri.com\/new\/?p=26811"},"modified":"2026-07-15T12:29:15","modified_gmt":"2026-07-15T18:29:15","slug":"aseguran-arsenal-y-equipo-tactico-en-punto-de-halconeo-en-gran-morelos","status":"publish","type":"post","link":"https:\/\/angelneri.com\/new\/2026\/07\/15\/aseguran-arsenal-y-equipo-tactico-en-punto-de-halconeo-en-gran-morelos\/","title":{"rendered":"Aseguran arsenal y equipo t\u00e1ctico en punto de halconeo en Gran Morelos"},"content":{"rendered":"<p>SSPE y la Defensa aseguraron en Gran Morelos armas de alto poder, cientos de cartuchos y equipo t\u00e1ctico en un presunto puesto de observaci\u00f3n; los indicios fueron entregados a la FGR.<\/p>\n<p>La Secretar\u00eda de Seguridad P\u00fablica del Estado (SSPE), en coordinaci\u00f3n con la Secretar\u00eda de la Defensa Nacional (DEFENSA), asegur\u00f3 armamento de alto poder, cientos de cartuchos y equipo t\u00e1ctico durante un operativo en Gran Morelos el 14 de julio.<\/p>\n<p>La intervenci\u00f3n se realiz\u00f3 tras atender un reporte ciudadano an\u00f3nimo que alertaba sobre la presencia de personas armadas en los alrededores del camino de terracer\u00eda Carretas\u2013Buenavista.<\/p>\n<p>Se implement\u00f3 un operativo interinstitucional que incluy\u00f3 recorridos terrestres y reconocimientos a\u00e9reos con una aeronave no tripulada.<\/p>\n<p>Con esa informaci\u00f3n se localiz\u00f3 un presunto puesto de observaci\u00f3n que, seg\u00fan las autoridades, era utilizado por integrantes de un grupo delictivo para vigilar la zona.<\/p>\n<p>Los elementos localizaron y aseguraron tres armas largas, entre ellas dos fusiles AK-47, un fusil tipo AR-15, 13 cargadores y 284 cartuchos \u00fatiles de distintos calibres, se\u00f1ala el reporte oficial.<\/p>\n<p>Entre el equipo t\u00e1ctico incautado, las autoridades consignaron tres chalecos, seis placas bal\u00edsticas, un porta cargadores de lona y un uniforme t\u00e1ctico con patr\u00f3n pixelado.<\/p>\n<p>tiempo.com.mx<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SSPE y la Defensa aseguraron en Gran Morelos armas de alto poder, cientos de cartuchos y equipo t\u00e1ctico en un presunto puesto de observaci\u00f3n; los indicios fueron entregados a la FGR. La Secretar\u00eda de Seguridad P\u00fablica del Estado (SSPE), en coordinaci\u00f3n con la Secretar\u00eda de la Defensa Nacional (DEFENSA), asegur\u00f3 armamento de alto poder, cientos [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":26812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-26811","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estado"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/angelneri.com\/new\/wp-content\/uploads\/2026\/07\/3232323323.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/posts\/26811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/comments?post=26811"}],"version-history":[{"count":1,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/posts\/26811\/revisions"}],"predecessor-version":[{"id":26813,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/posts\/26811\/revisions\/26813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/media\/26812"}],"wp:attachment":[{"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/media?parent=26811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/categories?post=26811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/tags?post=26811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}