{"id":26847,"date":"2026-07-15T13:34:50","date_gmt":"2026-07-15T19:34:50","guid":{"rendered":"https:\/\/angelneri.com\/new\/?p=26847"},"modified":"2026-07-15T13:34:50","modified_gmt":"2026-07-15T19:34:50","slug":"gobierno-de-mexico-rechaza-declaraciones-de-la-dea-sobre-vinculo-con-carteles","status":"publish","type":"post","link":"https:\/\/angelneri.com\/new\/2026\/07\/15\/gobierno-de-mexico-rechaza-declaraciones-de-la-dea-sobre-vinculo-con-carteles\/","title":{"rendered":"Gobierno de M\u00e9xico rechaza declaraciones de la DEA sobre v\u00ednculo con c\u00e1rteles"},"content":{"rendered":"<p>M\u00e9xico.- El Gabinete de Seguridad rechaz\u00f3 este martes las declaraciones del director de la DEA, Terry Cole, quien afirm\u00f3 que existe una \u201cconexi\u00f3n mortal\u201d entre los c\u00e1rteles de la droga y el gobierno mexicano y que ambos \u201cson lo mismo\u201d.<\/p>\n<p>En una tarjeta informativa, el gobierno se\u00f1al\u00f3 que las afirmaciones carecen de sustento y no corresponden a los resultados p\u00fablicos en el combate a la delincuencia organizada. Desde el 1 de octubre de 2024 al 30 de junio de 2026 han sido detenidas 59 mil 582 personas, entre ellas m\u00e1s de 80 servidores y exservidores p\u00fablicos, incluidos siete presidentes municipales en funciones.<\/p>\n<p>Tambi\u00e9n report\u00f3 el decomiso de 31 mil 366 armas de fuego y 498 toneladas de droga, entre ellas 2.3 toneladas y 5.5 millones de pastillas de fentanilo. Adem\u00e1s, se inhabilitaron 2 mil 627 laboratorios clandestinos para elaborar metanfetaminas.<\/p>\n<p>Entre septiembre de 2024 y junio de 2026, el promedio diario de homicidios dolosos disminuy\u00f3 48%. El gobierno sostuvo que su Estrategia Nacional de Seguridad se basa en una pol\u00edtica de \u201ccero impunidad\u201d y que la cooperaci\u00f3n bilateral con Estados Unidos ha permitido detener a objetivos prioritarios.<\/p>\n<p>Las declaraciones de Cole fueron hechas en la conferencia \u2018Fentanyl Free America\u2019, en Orlando, Florida, donde asegur\u00f3 que el combate a los c\u00e1rteles y a quienes facilitan sus operaciones es la principal prioridad de la DEA, al sostener que esas redes mantienen v\u00ednculos con funcionarios mexicanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- El Gabinete de Seguridad rechaz\u00f3 este martes las declaraciones del director de la DEA, Terry Cole, quien afirm\u00f3 que existe una \u201cconexi\u00f3n mortal\u201d entre los c\u00e1rteles de la droga y el gobierno mexicano y que ambos \u201cson lo mismo\u201d. En una tarjeta informativa, el gobierno se\u00f1al\u00f3 que las afirmaciones carecen de sustento y no [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":26848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[18],"tags":[],"class_list":["post-26847","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacional"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/angelneri.com\/new\/wp-content\/uploads\/2026\/07\/454564564664.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/posts\/26847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/comments?post=26847"}],"version-history":[{"count":1,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/posts\/26847\/revisions"}],"predecessor-version":[{"id":26849,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/posts\/26847\/revisions\/26849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/media\/26848"}],"wp:attachment":[{"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/media?parent=26847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/categories?post=26847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/tags?post=26847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}