{"id":4742,"date":"2024-03-15T14:15:49","date_gmt":"2024-03-15T20:15:49","guid":{"rendered":"https:\/\/angelneri.com\/new\/?p=4742"},"modified":"2024-03-15T14:15:59","modified_gmt":"2024-03-15T20:15:59","slug":"roban-pertenencias-de-interior-de-vehiculo-en-estacionamiento-de-alsuper-usaron-tecnica-del-cristalazo","status":"publish","type":"post","link":"https:\/\/angelneri.com\/new\/2024\/03\/15\/roban-pertenencias-de-interior-de-vehiculo-en-estacionamiento-de-alsuper-usaron-tecnica-del-cristalazo\/","title":{"rendered":"Roban pertenencias de interior de veh\u00edculo en estacionamiento de Alsuper, usaron t\u00e9cnica del cristalazo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Direcci\u00f3n de Seguridad P\u00fablica, atendi\u00f3 la tarde del jueves un llamado en el que solicitaron la presencia de Polic\u00edas Municipales en el estacionamiento de Alsuper fundadores, pues de acuerdo a la versi\u00f3n oficial, tras un cristalazo a un veh\u00edculo, robaron del interior un bolso de mano con dinero en efectivo, sin embargo, no se di\u00f3 a conocer el monto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a la version oficial por parte del Coordinador de Seguridad P\u00fablica Gilberto Terrazas, explic\u00f3 que: \u00abA las 14:10 horas del dia 14 de marzo, se acudi\u00f3 a la avenida ferrocarril y calzada del charro oriente en el centro comercial alsuper donde reportaron los da\u00f1os al cristal\u00bb. mencion\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/angelneri.com\/new\/wp-content\/uploads\/2024\/03\/image-123-1024x576.png\" alt=\"\" class=\"wp-image-4744\" srcset=\"https:\/\/angelneri.com\/new\/wp-content\/uploads\/2024\/03\/image-123-1024x576.png 1024w, https:\/\/angelneri.com\/new\/wp-content\/uploads\/2024\/03\/image-123-300x169.png 300w, https:\/\/angelneri.com\/new\/wp-content\/uploads\/2024\/03\/image-123-768x432.png 768w, https:\/\/angelneri.com\/new\/wp-content\/uploads\/2024\/03\/image-123-1536x864.png 1536w, https:\/\/angelneri.com\/new\/wp-content\/uploads\/2024\/03\/image-123-150x84.png 150w, https:\/\/angelneri.com\/new\/wp-content\/uploads\/2024\/03\/image-123-696x392.png 696w, https:\/\/angelneri.com\/new\/wp-content\/uploads\/2024\/03\/image-123-1068x601.png 1068w, https:\/\/angelneri.com\/new\/wp-content\/uploads\/2024\/03\/image-123.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que: \u00abAparte de los da\u00f1os al veh\u00edculo, se report\u00f3 el robo de un bolso de mano que conten\u00eda dinero en efectivo, por lo que tambi\u00e9n se dio aviso a Polic\u00eda Ministerial y Servicios Periciales, ya que se contaba con manchas hematicas en la escena, la cual se entreg\u00f3 a estos \u00faltimos par\u00e1 el seguimiento de la investigaciones\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n de Seguridad P\u00fablica, atendi\u00f3 la tarde del jueves un llamado en el que solicitaron la presencia de Polic\u00edas Municipales en el estacionamiento de Alsuper fundadores, pues de acuerdo a la versi\u00f3n oficial, tras un cristalazo a un veh\u00edculo, robaron del interior un bolso de mano con dinero en efectivo, sin embargo, no se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4743,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-4742","post","type-post","status-publish","format-standard","has-post-thumbnail","category-uncategorized"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/angelneri.com\/new\/wp-content\/uploads\/2024\/03\/image-122.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/posts\/4742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/comments?post=4742"}],"version-history":[{"count":2,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/posts\/4742\/revisions"}],"predecessor-version":[{"id":4746,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/posts\/4742\/revisions\/4746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/media\/4743"}],"wp:attachment":[{"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/media?parent=4742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/categories?post=4742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angelneri.com\/new\/wp-json\/wp\/v2\/tags?post=4742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}